{"id":18294,"date":"2020-04-01T09:30:50","date_gmt":"2020-04-01T07:30:50","guid":{"rendered":"https:\/\/www.bett1.at\/infoportal\/?p=18294"},"modified":"2025-11-06T16:08:24","modified_gmt":"2025-11-06T15:08:24","slug":"schlafparalyse","status":"publish","type":"post","link":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse","title":{"rendered":"Schlafparalyse was tun? Ursachen, Folgen und Behandlung von Wachschlaf"},"content":{"rendered":"\n<p>Der Begriff Schlafparalyse meint die nat\u00fcrliche L\u00e4hmung der menschlichen Muskulatur w\u00e4hrend des Schlafs. Die Schlafl\u00e4hmung wird normalerweise nicht wahrgenommen und verschwindet, sobald wir aufwachen. Bei einer Schlaf-wach-St\u00f6rung kann es passieren, dass du w\u00e4hrend des Schlafens erwachst und die L\u00e4hmung bewusst erlebst. In diesem Fall wird die Schlafparalyse als Schlafst\u00f6rung eingeordnet: Betroffene sind in diesem Zustand zwar wach, aber der K\u00f6rper ist f\u00fcr kurze Zeit v\u00f6llig bewegungsunf\u00e4hig. Damit k\u00f6nnen schlimme und realistisch anmutende Halluzinationen einhergehen, die Angst- und Panikgef\u00fchle hervorrufen. Das macht die Schlafparalyse zu einer der unheimlichsten Schlafst\u00f6rungen, die in der Regel jedoch ungef\u00e4hrlich ist.<\/p>\n\n\n<nav id=\"sommaire-article\"><a href=\"#schlafparalyse-als-schlafstoerung\" class=\"title_lvl2\"><span class=\"title_lvl\">1. <\/span>Schlafparalyse als Schlafst\u00f6rung<\/a><a href=\"#ursachen-fuer-schlafparalyse\" class=\"title_lvl2\"><span class=\"title_lvl\">2. <\/span>Ursachen f\u00fcr Schlafparalyse<\/a><a href=\"#was-hinter-dem-phaenomen-schlafparalyse-steckt\" class=\"title_lvl2\"><span class=\"title_lvl\">3. <\/span>Was hinter dem Ph\u00e4nomen Schlafparalyse steckt<\/a><a href=\"#ist-schlafparalyse-gefaehrlich\" class=\"title_lvl2\"><span class=\"title_lvl\">4. <\/span>Ist Schlafparalyse gef\u00e4hrlich?<\/a><a href=\"#schlafparalyse-behandlung\" class=\"title_lvl2\"><span class=\"title_lvl\">5. <\/span>Schlafparalyse Behandlung<\/a><a href=\"#wachschlaf-verbindung-von-schlafparalyse-und-luziden-traeumen\" class=\"title_lvl2\"><span class=\"title_lvl\">6. <\/span>Wachschlaf: Verbindung von Schlafparalyse und luziden Tr\u00e4umen<\/a><a href=\"#kulturelle-verbreitung-von-mythen-und-daemonen\" class=\"title_lvl2\"><span class=\"title_lvl\">7. <\/span>Kulturelle Verbreitung \u2013 von Mythen und D\u00e4monen<\/a><a href=\"#mythische-ursachen-der-schlafparalyse\" class=\"title_lvl3\"><span class=\"title_lvl\">7.1. <\/span>Mythische Ursachen der Schlafparalyse<\/a><a href=\"#kulturelle-verbreitung-in-der-heutigen-zeit\" class=\"title_lvl3\"><span class=\"title_lvl\">7.2. <\/span>Kulturelle Verbreitung in der heutigen Zeit<\/a><a href=\"#kategorien-der-schlafparalyse-halluzinationen\" class=\"title_lvl2\"><span class=\"title_lvl\">8. <\/span>Kategorien der Schlafparalyse-Halluzinationen<\/a><a href=\"#der-alb\" class=\"title_lvl3\"><span class=\"title_lvl\">8.1. <\/span>Der Alb<\/a><a href=\"#der-eindringling\" class=\"title_lvl3\"><span class=\"title_lvl\">8.2. <\/span>Der Eindringling<\/a><a href=\"#ungewoehnliche-koerperliche-erfahrungen\" class=\"title_lvl3\"><span class=\"title_lvl\">8.3. <\/span>Ungew\u00f6hnliche k\u00f6rperliche Erfahrungen<\/a><\/nav>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-schlafparalyse-als-schlafstorung\">Schlafparalyse als Schlafst\u00f6rung<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"446\" src=\"https:\/\/static.bett1.at\/2025\/03\/9e4367a6-bett1-schlafparalyse_optische_halluzination.jpg\" alt=\"Foto: Nahaufnahme von einem Auge, das weit ge\u00f6ffnet ist.\" class=\"wp-image-18454\" srcset=\"https:\/\/static.bett1.at\/2025\/03\/9e4367a6-bett1-schlafparalyse_optische_halluzination.jpg 1024w, https:\/\/static.bett1.at\/2025\/03\/9e4367a6-bett1-schlafparalyse_optische_halluzination-300x131.jpg 300w, https:\/\/static.bett1.at\/2025\/03\/9e4367a6-bett1-schlafparalyse_optische_halluzination-768x335.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<p>Bei der Schlafparalyse als Schlafst\u00f6rung wird die L\u00e4hmung der Muskulatur kurz nach dem Aufwachen bewusst erlebt. Betroffene besitzen keinerlei Kontrolle \u00fcber ihren K\u00f6rper. Bei der Mehrheit der Betroffenen geht dieser Zustand mit furchterregenden Halluzinationen einher, die sie als besonders plastisch und realistisch beschreiben. Dabei k\u00f6nnen imagin\u00e4re Monster oder sonstige d\u00fcstere Gestalten in Erscheinung treten. Fast immer entwickelt sich daraus eine bedrohliche Situation, die eine Gefahr f\u00fcr die Betroffenen darstellt und gegen die sie wehrlos sind. Durch die K\u00f6rperl\u00e4hmung der Schlafparalyse sind Betroffene wie erstarrt: Es gibt kein Entkommen. Die Halluzinationen werden meist als bedrohlicher als die K\u00f6rperstarre selbst wahrgenommen, was zu Angst und Panik f\u00fchren kann. H\u00e4ufig berichten Betroffene au\u00dferdem von einem Druckgef\u00fchl auf der Brust. Kurzatmigkeit und das Gef\u00fchl zu ersticken sind typische Symptome. Nach wenigen Sekunden ist der Spuk vorbei, doch der Schock steckt vielen Menschen noch lange Zeit nach dem gruseligen Erlebnis in den Knochen.<\/p>\n\n\n\n<p>Die schlafparalytische L\u00e4hmungserfahrung kann als das Gegenteil vom Schlafwandeln beschrieben werden: Beim Schlafwandeln schl\u00e4ft der Geist, w\u00e4hrend der K\u00f6rper wach wird und sich in Bewegung setzt. Bei der Schlafl\u00e4hmung ist der Geist wach, der K\u00f6rper schl\u00e4ft jedoch.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ursachen-fur-schlafparalyse\">Ursachen f\u00fcr Schlafparalyse<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"541\" src=\"https:\/\/static.bett1.at\/2025\/03\/32104946-bett1-schlafparalyse_depression_stress_ausloeser_paralyse.jpg\" alt=\"Auf einem grauen Hintergrund ist der Scherenschnitt eines gesenkten Kopfes. Zerkn\u00fcllte Papierkugeln liegen darauf.\" class=\"wp-image-18446\" srcset=\"https:\/\/static.bett1.at\/2025\/03\/32104946-bett1-schlafparalyse_depression_stress_ausloeser_paralyse.jpg 1024w, https:\/\/static.bett1.at\/2025\/03\/32104946-bett1-schlafparalyse_depression_stress_ausloeser_paralyse-300x158.jpg 300w, https:\/\/static.bett1.at\/2025\/03\/32104946-bett1-schlafparalyse_depression_stress_ausloeser_paralyse-768x406.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Die h\u00e4ufigsten Ursachen der Schlafparalyse stehen in Verbindung mit schlechtem oder zu wenig Schlaf. Unregelm\u00e4\u00dfiger Schlaf und Schlafmangel beg\u00fcnstigen das bewusste Erleben einer Schlafl\u00e4hmung. Zudem ist die Schlafstarre eine typische Begleiterscheinung bei Narkolepsie, eine neurologische Erkrankung, die \u00fcberfallartige Einschlafattacken hervorruft. Nicht selten sind innerliche Konflikte oder Stress der Grund f\u00fcr eine Schlafparalyse, denn laut Schlafmedizin werden Konflikte und besonders emotionale Situationen in unseren Tr\u00e4umen verarbeitet. Angstzust\u00e4nde und Depressionen sind ebenfalls bekannte Faktoren f\u00fcr das Erleben der Schlafstarre.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Was sind Ursachen einer Schlafparalyse?<\/strong><\/td><\/tr><tr><td>Schlafentzug<\/td><\/tr><tr><td>Schlafmangel<\/td><\/tr><tr><td>Narkolepsie<\/td><\/tr><tr><td>Depressionen<\/td><\/tr><tr><td>Angstzust\u00e4nde<\/td><\/tr><tr><td>Stress<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-was-hinter-dem-phanomen-schlafparalyse-steckt\">Was hinter dem Ph\u00e4nomen Schlafparalyse steckt<\/h2>\n\n\n\n<p>Hinter der Schlafparalyse steckt ein harmloser Vorgang, der sich jede Nacht wiederholt und w\u00e4hrend der REM-Phase einsetzt: Sobald wir einschlafen, entspannt sich der K\u00f6rper. Dabei kommt es im Verlauf zu einer nat\u00fcrlichen Bewegungseinschr\u00e4nkung der Muskulatur, die wir nicht wahrnehmen. Ausgenommen davon ist die Augenmuskulatur. Dieser Vorgang wird als REM-Atonie bezeichnet, der als Schutzmechanismus dient. Um das Ausleben der Tr\u00e4ume und damit eventuell verbundene Unf\u00e4lle zu vermeiden, paralysiert das Gehirn den K\u00f6rper. Tr\u00e4umst du beispielsweise vom Fahrradfahren, w\u00fcrdest du ohne diesen Schutzmechanismus im Bett in die Pedale treten. Normalerweise sind die \u00dcberg\u00e4nge von Wach- und Schlafzustand flie\u00dfend, hin und wieder kommt es jedoch zu einer \u00dcberschneidung. In diesem Fall kann eine bewusst erlebte Schlafstarre eintreten: Du erwachst direkt aus der REM-Phase und \u00fcberspringst die Aufwachphase. Das geschieht vor allem dann, wenn du einen Albtraum hast. Deshalb sieht die Schlafmedizin einen Zusammenhang zwischen den auftretenden Halluzinationen mit unseren Tr\u00e4umen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"446\" src=\"https:\/\/static.bett1.at\/2025\/03\/d5233304-bett1-schlafparalyse_halluzination_traum_aufwachen.jpg\" alt=\"Foto: Eine Person h\u00e4lt sich die Finger vor die Augen. Neben ihr diffuses buntes Licht\" class=\"wp-image-18448\" srcset=\"https:\/\/static.bett1.at\/2025\/03\/d5233304-bett1-schlafparalyse_halluzination_traum_aufwachen.jpg 1024w, https:\/\/static.bett1.at\/2025\/03\/d5233304-bett1-schlafparalyse_halluzination_traum_aufwachen-300x131.jpg 300w, https:\/\/static.bett1.at\/2025\/03\/d5233304-bett1-schlafparalyse_halluzination_traum_aufwachen-768x335.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<div class=\"box grey-box\"><\/p>\n\n\n\n<p><strong>Wissenswert: <\/strong>Knapp acht Prozent der Gesamtbev\u00f6lkerung erleben mindestens einmal im Leben eine bewusste Schlafparalyse. Die Schlafst\u00f6rung tritt in manchen F\u00e4llen sogar mehr als einmal auf. Menschen, die an psychischen Erkrankungen wie Depressionen oder Angstzust\u00e4nden leiden, sind mit knapp 23 Prozent am h\u00e4ufigsten von der Schlafparalyse betroffen.<\/p>\n\n\n<p><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ist-schlafparalyse-gefahrlich\">Ist Schlafparalyse gef\u00e4hrlich?<\/h2>\n\n\n\n<p>Viele Menschen fragen sich, ob die Schlafparalyse gef\u00e4hrlich ist. Sie bef\u00fcrchten, dass die Atmung w\u00e4hrend einer Schlafparalyse komplett aussetzt oder das Herz aufh\u00f6rt zu schlagen. Hierf\u00fcr gibt es keinerlei anatomische Anhaltspunkte: Atmung und <a href=\"https:\/\/www.bett1.at\/infoportal\/ratgeber\/herzrasen-nachts-puls-beim-schlafen-puls-im-schlaf\">Herzschlag<\/a> werden automatisch fortgesetzt, auch w\u00e4hrend wir schlafen und tr\u00e4umen. K\u00f6rperlich ist die Schlafparalyse also ungef\u00e4hrlich, kann auf Dauer jedoch zu einer psychischen Belastung und Beeintr\u00e4chtigung des Allgemeinwohls f\u00fchren. Leidest du unter regelm\u00e4\u00dfig wiederkehrender Schlafparalyse, scheue dich nicht, dir medizinische Hilfe zu holen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"446\" src=\"https:\/\/static.bett1.at\/2025\/03\/98ebf3b4-bett1-schlafparalyse_auswirkungen_druck_auf_brust_panik.jpg\" alt=\"Foto: Eine unbekleidete Person sitzt im dunklen Zimmer und fasst sich an die Brust.\" class=\"wp-image-18452\" srcset=\"https:\/\/static.bett1.at\/2025\/03\/98ebf3b4-bett1-schlafparalyse_auswirkungen_druck_auf_brust_panik.jpg 1024w, https:\/\/static.bett1.at\/2025\/03\/98ebf3b4-bett1-schlafparalyse_auswirkungen_druck_auf_brust_panik-300x131.jpg 300w, https:\/\/static.bett1.at\/2025\/03\/98ebf3b4-bett1-schlafparalyse_auswirkungen_druck_auf_brust_panik-768x335.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"h-schlafparalyse-behandlung\">Schlafparalyse Behandlung<\/h2>\n\n\n\n<p>Bisher gibt es keine wirksame Therapie gegen die Schlafstarre, sie l\u00e4sst sich unter Umst\u00e4nden jedoch abmildern. Bereits durch die kleinste Bewegung kann eine Schlafparalyse durchbrochen werden. W\u00e4hrend der L\u00e4hmung hilft es oftmals, sich darauf zu konzentrieren, die Augen oder den kleinen Finger zu bewegen. In schwerwiegenden F\u00e4llen kann eine Psychotherapie helfen und die Einnahme von Antidepressiva oder anderen <a href=\"https:\/\/de.wikipedia.org\/wiki\/Neuroleptikum\">Neuroleptika<\/a>, die eventuelle tiefgreifendere Ursachen beheben. Wichtig ist, die m\u00f6glichen Ausl\u00f6ser so gut es geht zu meiden. Du solltest daher f\u00fcr einen guten und ausreichend langen Schlaf sorgen und die Einhaltung einer Schlafhygiene beachten. Zudem ist es ratsam, m\u00f6glichst nicht auf dem R\u00fccken zu schlafen. Untersuchungen ergaben, dass eine Schlafparalyse drei- bis viermal h\u00e4ufiger auftritt, wenn du auf dem R\u00fccken liegst.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"446\" src=\"https:\/\/static.bett1.at\/2025\/03\/ac725aaa-bett1-schlafparalyse_hilfe_besser_schlafen_arzt_medikamente.jpg\" alt=\"Foto: Eine Person liegt mit geschlossenen Augen im Bett. Durchs Fenster strahlt die Sonne herein.\" class=\"wp-image-18453\" srcset=\"https:\/\/static.bett1.at\/2025\/03\/ac725aaa-bett1-schlafparalyse_hilfe_besser_schlafen_arzt_medikamente.jpg 1024w, https:\/\/static.bett1.at\/2025\/03\/ac725aaa-bett1-schlafparalyse_hilfe_besser_schlafen_arzt_medikamente-300x131.jpg 300w, https:\/\/static.bett1.at\/2025\/03\/ac725aaa-bett1-schlafparalyse_hilfe_besser_schlafen_arzt_medikamente-768x335.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"h-wachschlaf-verbindung-von-schlafparalyse-und-luziden-traumen\">Wachschlaf: Verbindung von Schlafparalyse und luziden Tr\u00e4umen<\/h2>\n\n\n\n<p>Die Schlafparalyse l\u00e4sst sich durch bestimmte Techniken zum luziden Tr\u00e4umen hervorrufen. Beim luziden Tr\u00e4umen oder einem Klartraum kann die Person einen <a href=\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/traumdeutung-traumsymbole\">Traum<\/a> selbst steuern. Den Zustand von bewusstem Wachsschlaf kannst du durch verschiedene Techniken lernen. Das gelingt, indem du gezielt bewusst \u2013 erneut \u2013 einschl\u00e4fst und direkt in einen Klartraum \u00fcbergehst oder lernst den Traumzustand zu erkennen und so in den Wachschlaf zu wechseln. Den Traum selbst kannst du in dieser Form der Schlafparalyse im Gegensatz zu deinem K\u00f6rper beeinflussen und steuern.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-kulturelle-verbreitung-von-mythen-und-damonen\">Kulturelle Verbreitung \u2013 von Mythen und D\u00e4monen<\/h2>\n\n\n\n<p>Schon seit jeher thematisieren Menschen und Kulturen die Schlafparalyse als n\u00e4chtliche Heimsuchung durch D\u00e4monen oder furchteinfl\u00f6\u00dfende Kreaturen. Den Halluzinationen wurden dabei religi\u00f6se oder volkst\u00fcmliche Bedeutungen zugeschrieben. Bereits in der griechischen Mythologie ist die Rede von Pan, dem Hirtengott, der mit Ziegenf\u00fc\u00dfen, H\u00f6rnern und einem Bart zur Welt kam und mit der Schlafparalyse in Verbindung gebracht wird. F\u00fchlte sich Pan ver\u00e4rgert, jagte er seine Opfer so lange, bis sie schlie\u00dflich vor Panik starben. Im Mittelalter glaubten viele Menschen daran, dass das Ph\u00e4nomen mit dem Teufel und D\u00e4monen in Verbindung steht. Man ging davon aus, dass die Schlafparalysierten von Kreaturen aus der Unterwelt heimgesucht wurden. Religi\u00f6se Gemeinschaften sahen darin oft Hexerei, was dazu f\u00fchrte, dass viele Betroffene auf dem Scheiterhaufen endeten.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"446\" src=\"https:\/\/static.bett1.at\/2025\/03\/ad5dfe27-bett1-schlafparalyse_fabelwesen_pan_herkunft.jpg\" alt=\"Foto: Frontaler Blick eines in rotes Licht getauchten Ziegenbocks mit gesenktem Geweih.\" class=\"wp-image-18449\" srcset=\"https:\/\/static.bett1.at\/2025\/03\/ad5dfe27-bett1-schlafparalyse_fabelwesen_pan_herkunft.jpg 1024w, https:\/\/static.bett1.at\/2025\/03\/ad5dfe27-bett1-schlafparalyse_fabelwesen_pan_herkunft-300x131.jpg 300w, https:\/\/static.bett1.at\/2025\/03\/ad5dfe27-bett1-schlafparalyse_fabelwesen_pan_herkunft-768x335.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-mythische-ursachen-der-schlafparalyse\">Mythische Ursachen der Schlafparalyse<\/h3>\n\n\n\n<p>Weiterhin war die Vorstellung weit verbreitet, dass ein D\u00e4mon auf der Brust des Schlafenden sitzt und ihm auf diese Weise die Luft zum Atmen nimmt. Daher wird Schlafparalyse im Volksmund auch als Hexendr\u00fccken oder Albdruck bezeichnet. In der germanischen Mythologie war der Nachtalb, fr\u00fcher genannt Nachtmahr, ein Fantasiewesen, das seine Opfer in der Nacht aufsuchte und auf ihnen lastete. Die dunklen koboldhaften, t\u00fcckischen Wesen drangen durch Schl\u00fcssell\u00f6cher in das Schlafzimmer ein und hockten sich auf die Brust der Schlafenden. Dies erzeugte ein unangenehmes Druckgef\u00fchl auf der Brust bis hin zu Atemnot. Die bekannteste k\u00fcnstlerische Veranschaulichung dieses Ph\u00e4nomens ist das Gem\u00e4lde \u201eNachtmahr\u201c (1781) von Johann Heinrich F\u00fcssli. Der Nachtalb sitzt auf der Brust einer schlafenden, wehrlosen Frau und schaut die Betrachtenden direkt an.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-kulturelle-verbreitung-in-der-heutigen-zeit\"><a id=\"Verbreitung\" class=\"anchor\"><\/a>Kulturelle Verbreitung in der heutigen Zeit<\/h3>\n\n\n\n<p>In vielen weiteren L\u00e4ndern und Kulturen wird das Ph\u00e4nomen noch heute sehr metaphorisch beschrieben: In Irland, Schottland und Kanada sind es Hexen, die einen in der Nacht aufsuchen, in S\u00fcdostasien vorwiegend Geister von Verstorbenen. In den USA wird die Schlafparalyse, eigentlich \u201esleep paralysis\u201c, auch als \u201eshadow people\u201c (Schattenmenschen) bezeichnet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-kategorien-der-schlafparalyse-halluzinationen\">Kategorien der Schlafparalyse-Halluzinationen<\/h2>\n\n\n\n<p>Eine Langzeitstudie aus dem Jahr 1999 hat sich mit Erfahrungsberichten zur Schlafparalyse besch\u00e4ftigt. Dabei wurden insbesondere die Schlafparalyse Halluzinationen unter die Lupe genommen und analysiert. Letztendlich lassen sich nach der Untersuchung drei Hauptkategorien von Schlafparalyse-Halluzinationen definieren:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"523\" src=\"https:\/\/static.bett1.at\/2025\/03\/ceb4f4dd-bett1-schlafparalyse_luzides_traeumen.jpg\" alt=\"Eine Leiter ragt in den Himmel und verschwindet in einer Wolke.\" class=\"wp-image-18450\" srcset=\"https:\/\/static.bett1.at\/2025\/03\/ceb4f4dd-bett1-schlafparalyse_luzides_traeumen.jpg 1024w, https:\/\/static.bett1.at\/2025\/03\/ceb4f4dd-bett1-schlafparalyse_luzides_traeumen-300x153.jpg 300w, https:\/\/static.bett1.at\/2025\/03\/ceb4f4dd-bett1-schlafparalyse_luzides_traeumen-768x392.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-der-alb\"><a id=\"Alb\" class=\"anchor\"><\/a>Der Alb<\/h3>\n\n\n\n<p>Neben \u00fcberwiegend akustisch auftretenden Halluzinationen versp\u00fcren Betroffene den typischen Druck auf ihrer Brust, was mit dem Gef\u00fchl einhergeht, kaum atmen zu k\u00f6nnen. Die Forschung betont, dass dieses Gef\u00fchl der subjektiven Wahrnehmung einer Schlafparalyse entspricht. Da die Atmung ein Reflex ist, funktioniert sie automatisch. Dass uns die <a href=\"https:\/\/www.bett1.at\/infoportal\/ratgeber\/sauerstoffsaettigung-im-schlaf-pulsoximeter\">Sauerstoffzufuhr<\/a> abgeschnitten wird, ist daher nicht real. Die Atmung in der REM-Phase ist nat\u00fcrlich abgeflacht, was den subjektiven Eindruck herbeif\u00fchrt und verst\u00e4rkt. Wirst du in dieser Phase wach, kann sich die Atmung erschwert anf\u00fchlen, was wiederum Angst vor dem Ersticken ausl\u00f6sen kann.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-der-eindringling\"><a id=\"Eindringling\" class=\"anchor\"><\/a>Der Eindringling<\/h3>\n\n\n\n<p>In diesem Fall treten die Halluzinationen vor allem visuell auf. Betroffene sehen eine Gestalt oder eine furchteinfl\u00f6\u00dfende Pr\u00e4senz, was Panik ausl\u00f6sen kann. Der Eindringling und der Alb treten in den meisten F\u00e4llen zusammen in Erscheinung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-ungewohnliche-korperliche-erfahrungen\"><a id=\"ungew\u00f6hnlich\" class=\"anchor\"><\/a>Ungew\u00f6hnliche k\u00f6rperliche Erfahrungen<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/bett1-328410-infoportal-prod-de\/2020\/04\/bett1-schlafparalyse_ausserkoerperliche_erfahrung_schweben-241x300.jpg\" alt=\"Eine von einem Tuch bedeckte Silhouette liegt schwebend in einem schwarzen Raum. Arme und Beine h\u00e4ngen herab.\" class=\"wp-image-18451\"\/><\/figure>\n<\/div>\n\n\n<p>Diese Kategorie ist die mit Abstand seltenste Form der Halluzinationen. Betroffene berichten von einer au\u00dferk\u00f6rperlichen Erfahrung. Sie beschreiben, wie sie durch den Raum schweben oder gleiten. Viele sehen ihren eigenen K\u00f6rper von oben aus der Luft im Bett liegen. In einer Studie aus dem Jahr 2013 mit 133 Teilnehmenden, die an Panikst\u00f6rungen litten, sehen Forschende einen Zusammenhang mit einer \u00dcberaktivit\u00e4t gewisser Hirnstr\u00e4nge.<\/p>\n\n\n\n<p>Die Wissenschaft geht davon aus, dass die Halluzinationen stark abh\u00e4ngig von Zeit und Kultur der Betroffenen sind. Nicht zuletzt ist die Erscheinung des n\u00e4chtlichen Besuchs vom pers\u00f6nlichen Umfeld, Glauben und Erfahrungen Betroffener gepr\u00e4gt. Glaubten fr\u00fcher viele an Hexen und D\u00e4monen, so sind es heute Au\u00dferirdische und paranormale Gestalten von denen Betroffene der Schlafparalyse berichten. Die Halluzinationen sind oft so real, dass einige Menschen regelrecht \u00fcberzeugt von der Annahme sind, schon einmal von Au\u00dferirdischen entf\u00fchrt worden zu sein. Die Forschung sieht in den Halluzinationen das Produkt unserer dunkelsten \u00c4ngste. Ausreichend belegt ist diese Annahme jedoch nicht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Begriff Schlafparalyse meint die nat\u00fcrliche L\u00e4hmung der menschlichen Muskulatur w\u00e4hrend des Schlafs. Die Schlafl\u00e4hmung wird normalerweise nicht wahrgenommen und verschwindet, sobald wir aufwachen. Bei einer Schlaf-wach-St\u00f6rung kann es passieren, dass du w\u00e4hrend des Schlafens erwachst und die L\u00e4hmung bewusst erlebst. In diesem Fall wird die Schlafparalyse als Schlafst\u00f6rung eingeordnet: Betroffene sind in diesem Zustand [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":18445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[363,374,378,379,386],"class_list":["post-18294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schlafgeschichten","tag-schlafentzug","tag-schlafmangel","tag-schlafparalyse","tag-schlafphaenomene","tag-schlafstoerung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v26.9-RC2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Schlafparalyse was tun? Ursachen, Folgen und Behandlung von Wachschlaf - Infoportal<\/title>\n<meta name=\"description\" content=\"Schlafparalyse | Das bewusste Erleben einer Schlafl\u00e4hmung | Ist die Schlafl\u00e4hmung gef\u00e4hrlich? | Schlafmangel beg\u00fcnstigt eine bewusste Schlafl\u00e4hmung |\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schlafparalyse was tun? Ursachen, Folgen und Behandlung von Wachschlaf\" \/>\n<meta property=\"og:description\" content=\"Schlafparalyse | Das bewusste Erleben einer Schlafl\u00e4hmung | Ist die Schlafl\u00e4hmung gef\u00e4hrlich? | Schlafmangel beg\u00fcnstigt eine bewusste Schlafl\u00e4hmung |\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse\" \/>\n<meta property=\"og:site_name\" content=\"Infoportal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bett1.de\/?locale=de_DE\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-01T07:30:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T15:08:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.bett1.at\/2025\/03\/18cd4e10-bett1-schlafparalyse_header_mann_erstarrt_traumwelt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"657\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vanessa Giebel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vanessa Giebel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse\"},\"author\":{\"name\":\"Vanessa Giebel\",\"@id\":\"https:\/\/www.bett1.at\/infoportal\/#\/schema\/person\/168cec41fe2bca8f42676cc3c5a71a64\"},\"headline\":\"Schlafparalyse was tun? Ursachen, Folgen und Behandlung von Wachschlaf\",\"datePublished\":\"2020-04-01T07:30:50+00:00\",\"dateModified\":\"2025-11-06T15:08:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse\"},\"wordCount\":1659,\"publisher\":{\"@id\":\"https:\/\/www.bett1.at\/infoportal\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.bett1.at\/2025\/03\/18cd4e10-bett1-schlafparalyse_header_mann_erstarrt_traumwelt.jpg\",\"keywords\":[\"schlafentzug\",\"Schlafmangel\",\"Schlafparalyse\",\"Schlafph\u00e4nomene\",\"Schlafst\u00f6rung\"],\"articleSection\":[\"Schlafgeschichten\"],\"inLanguage\":\"de-AT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse\",\"url\":\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse\",\"name\":\"Schlafparalyse was tun? Ursachen, Folgen und Behandlung von Wachschlaf - Infoportal\",\"isPartOf\":{\"@id\":\"https:\/\/www.bett1.at\/infoportal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.bett1.at\/2025\/03\/18cd4e10-bett1-schlafparalyse_header_mann_erstarrt_traumwelt.jpg\",\"datePublished\":\"2020-04-01T07:30:50+00:00\",\"dateModified\":\"2025-11-06T15:08:24+00:00\",\"description\":\"Schlafparalyse | Das bewusste Erleben einer Schlafl\u00e4hmung | Ist die Schlafl\u00e4hmung gef\u00e4hrlich? | Schlafmangel beg\u00fcnstigt eine bewusste Schlafl\u00e4hmung |\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#breadcrumb\"},\"inLanguage\":\"de-AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#primaryimage\",\"url\":\"https:\/\/static.bett1.at\/2025\/03\/18cd4e10-bett1-schlafparalyse_header_mann_erstarrt_traumwelt.jpg\",\"contentUrl\":\"https:\/\/static.bett1.at\/2025\/03\/18cd4e10-bett1-schlafparalyse_header_mann_erstarrt_traumwelt.jpg\",\"width\":1200,\"height\":657,\"caption\":\"Foto: Zustand w\u00e4hrend einer Schlafparalyse: Ein Gesicht schaut in eine runden Spiegel mit grell leuchtendem Rahmen. Die Spiegelfl\u00e4che ist schwarz, eine Hand greift heraus Richtung Gesicht.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bett1.at\/infoportal\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schlafparalyse was tun? Ursachen, Folgen und Behandlung von Wachschlaf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bett1.at\/infoportal\/#website\",\"url\":\"https:\/\/www.bett1.at\/infoportal\/\",\"name\":\"Infoportal AT\",\"description\":\"bett1.at\",\"publisher\":{\"@id\":\"https:\/\/www.bett1.at\/infoportal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bett1.at\/infoportal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-AT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bett1.at\/infoportal\/#organization\",\"name\":\"bett1 Infoportal\",\"url\":\"https:\/\/www.bett1.at\/infoportal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\/\/www.bett1.at\/infoportal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.bett1.at\/2025\/07\/69f410f5-sticky-logo-at.webp\",\"contentUrl\":\"https:\/\/static.bett1.at\/2025\/07\/69f410f5-sticky-logo-at.webp\",\"width\":268,\"height\":128,\"caption\":\"bett1 Infoportal\"},\"image\":{\"@id\":\"https:\/\/www.bett1.at\/infoportal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/bett1.de\/?locale=de_DE\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bett1.at\/infoportal\/#\/schema\/person\/168cec41fe2bca8f42676cc3c5a71a64\",\"name\":\"Vanessa Giebel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\/\/www.bett1.at\/infoportal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/81cbe4e36710c21838378b66fa5ed3c6f42e479a7f9bd24a32a861b1307d1cdd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/81cbe4e36710c21838378b66fa5ed3c6f42e479a7f9bd24a32a861b1307d1cdd?s=96&d=mm&r=g\",\"caption\":\"Vanessa Giebel\"},\"url\":\"https:\/\/www.bett1.at\/infoportal\/author\/bett1-vanessa\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Schlafparalyse was tun? Ursachen, Folgen und Behandlung von Wachschlaf - Infoportal","description":"Schlafparalyse | Das bewusste Erleben einer Schlafl\u00e4hmung | Ist die Schlafl\u00e4hmung gef\u00e4hrlich? | Schlafmangel beg\u00fcnstigt eine bewusste Schlafl\u00e4hmung |","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse\/","og_locale":"de_DE","og_type":"article","og_title":"Schlafparalyse was tun? Ursachen, Folgen und Behandlung von Wachschlaf","og_description":"Schlafparalyse | Das bewusste Erleben einer Schlafl\u00e4hmung | Ist die Schlafl\u00e4hmung gef\u00e4hrlich? | Schlafmangel beg\u00fcnstigt eine bewusste Schlafl\u00e4hmung |","og_url":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse","og_site_name":"Infoportal","article_publisher":"https:\/\/www.facebook.com\/bett1.de\/?locale=de_DE","article_published_time":"2020-04-01T07:30:50+00:00","article_modified_time":"2025-11-06T15:08:24+00:00","og_image":[{"width":1200,"height":657,"url":"https:\/\/static.bett1.at\/2025\/03\/18cd4e10-bett1-schlafparalyse_header_mann_erstarrt_traumwelt.jpg","type":"image\/jpeg"}],"author":"Vanessa Giebel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Vanessa Giebel","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#article","isPartOf":{"@id":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse"},"author":{"name":"Vanessa Giebel","@id":"https:\/\/www.bett1.at\/infoportal\/#\/schema\/person\/168cec41fe2bca8f42676cc3c5a71a64"},"headline":"Schlafparalyse was tun? Ursachen, Folgen und Behandlung von Wachschlaf","datePublished":"2020-04-01T07:30:50+00:00","dateModified":"2025-11-06T15:08:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse"},"wordCount":1659,"publisher":{"@id":"https:\/\/www.bett1.at\/infoportal\/#organization"},"image":{"@id":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#primaryimage"},"thumbnailUrl":"https:\/\/static.bett1.at\/2025\/03\/18cd4e10-bett1-schlafparalyse_header_mann_erstarrt_traumwelt.jpg","keywords":["schlafentzug","Schlafmangel","Schlafparalyse","Schlafph\u00e4nomene","Schlafst\u00f6rung"],"articleSection":["Schlafgeschichten"],"inLanguage":"de-AT"},{"@type":"WebPage","@id":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse","url":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse","name":"Schlafparalyse was tun? Ursachen, Folgen und Behandlung von Wachschlaf - Infoportal","isPartOf":{"@id":"https:\/\/www.bett1.at\/infoportal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#primaryimage"},"image":{"@id":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#primaryimage"},"thumbnailUrl":"https:\/\/static.bett1.at\/2025\/03\/18cd4e10-bett1-schlafparalyse_header_mann_erstarrt_traumwelt.jpg","datePublished":"2020-04-01T07:30:50+00:00","dateModified":"2025-11-06T15:08:24+00:00","description":"Schlafparalyse | Das bewusste Erleben einer Schlafl\u00e4hmung | Ist die Schlafl\u00e4hmung gef\u00e4hrlich? | Schlafmangel beg\u00fcnstigt eine bewusste Schlafl\u00e4hmung |","breadcrumb":{"@id":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#breadcrumb"},"inLanguage":"de-AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse"]}]},{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#primaryimage","url":"https:\/\/static.bett1.at\/2025\/03\/18cd4e10-bett1-schlafparalyse_header_mann_erstarrt_traumwelt.jpg","contentUrl":"https:\/\/static.bett1.at\/2025\/03\/18cd4e10-bett1-schlafparalyse_header_mann_erstarrt_traumwelt.jpg","width":1200,"height":657,"caption":"Foto: Zustand w\u00e4hrend einer Schlafparalyse: Ein Gesicht schaut in eine runden Spiegel mit grell leuchtendem Rahmen. Die Spiegelfl\u00e4che ist schwarz, eine Hand greift heraus Richtung Gesicht."},{"@type":"BreadcrumbList","@id":"https:\/\/www.bett1.at\/infoportal\/schlafgeschichten\/schlafparalyse#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bett1.at\/infoportal"},{"@type":"ListItem","position":2,"name":"Schlafparalyse was tun? Ursachen, Folgen und Behandlung von Wachschlaf"}]},{"@type":"WebSite","@id":"https:\/\/www.bett1.at\/infoportal\/#website","url":"https:\/\/www.bett1.at\/infoportal\/","name":"Infoportal AT","description":"bett1.at","publisher":{"@id":"https:\/\/www.bett1.at\/infoportal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bett1.at\/infoportal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-AT"},{"@type":"Organization","@id":"https:\/\/www.bett1.at\/infoportal\/#organization","name":"bett1 Infoportal","url":"https:\/\/www.bett1.at\/infoportal\/","logo":{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/www.bett1.at\/infoportal\/#\/schema\/logo\/image\/","url":"https:\/\/static.bett1.at\/2025\/07\/69f410f5-sticky-logo-at.webp","contentUrl":"https:\/\/static.bett1.at\/2025\/07\/69f410f5-sticky-logo-at.webp","width":268,"height":128,"caption":"bett1 Infoportal"},"image":{"@id":"https:\/\/www.bett1.at\/infoportal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bett1.de\/?locale=de_DE"]},{"@type":"Person","@id":"https:\/\/www.bett1.at\/infoportal\/#\/schema\/person\/168cec41fe2bca8f42676cc3c5a71a64","name":"Vanessa Giebel","image":{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/www.bett1.at\/infoportal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/81cbe4e36710c21838378b66fa5ed3c6f42e479a7f9bd24a32a861b1307d1cdd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81cbe4e36710c21838378b66fa5ed3c6f42e479a7f9bd24a32a861b1307d1cdd?s=96&d=mm&r=g","caption":"Vanessa Giebel"},"url":"https:\/\/www.bett1.at\/infoportal\/author\/bett1-vanessa"}]}},"_links":{"self":[{"href":"https:\/\/www.bett1.at\/infoportal\/wp-json\/wp\/v2\/posts\/18294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bett1.at\/infoportal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bett1.at\/infoportal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bett1.at\/infoportal\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bett1.at\/infoportal\/wp-json\/wp\/v2\/comments?post=18294"}],"version-history":[{"count":4,"href":"https:\/\/www.bett1.at\/infoportal\/wp-json\/wp\/v2\/posts\/18294\/revisions"}],"predecessor-version":[{"id":162612,"href":"https:\/\/www.bett1.at\/infoportal\/wp-json\/wp\/v2\/posts\/18294\/revisions\/162612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bett1.at\/infoportal\/wp-json\/wp\/v2\/media\/18445"}],"wp:attachment":[{"href":"https:\/\/www.bett1.at\/infoportal\/wp-json\/wp\/v2\/media?parent=18294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bett1.at\/infoportal\/wp-json\/wp\/v2\/categories?post=18294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bett1.at\/infoportal\/wp-json\/wp\/v2\/tags?post=18294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}